{"id":4405,"date":"2014-08-27T12:53:16","date_gmt":"2014-08-27T10:53:16","guid":{"rendered":"http:\/\/www.manquepierda.com\/futbolandia\/?p=4405"},"modified":"2014-08-27T12:54:21","modified_gmt":"2014-08-27T10:54:21","slug":"salir-del-infierno","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/","title":{"rendered":"Salir del infierno."},"content":{"rendered":"<p style=\"text-align: left\">Mucho se ha escrito sobre el p\u00e9simo inicio de temporada que est\u00e1 firmando el Manchester United, que en tres partidos aun no ha conocido la victoria, a saber: derrota contra el Swansea, empate contra el Sunderland y una brutal paliza propinada por un equipo de League One como es el MK Dons en la ronda eliminatoria de la Capital One Cup, quiz\u00e1 el menos importante (o prestigioso) de los tres t\u00edtulos en liza para esta temporada del conjunto de Louis Van Gaal. Todas las flores de la pretemporada se han marchitado con el comienzo de la competici\u00f3n seria, e incluso algunos establecen una jocosa comparativa con el United de Moyes a estas alturas de la temporada pasada, por lo que deja un trasfondo no muy dif\u00edcil de analizar, y es que el entrenador no es el problema de esta entidad hist\u00f3rica, sino los que est\u00e1n sobre el verde.<\/p>\n<figure id=\"attachment_4407\" aria-describedby=\"caption-attachment-4407\" style=\"width: 594px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4407\" data-permalink=\"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/448326_heroa\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&amp;ssl=1\" data-orig-size=\"594,421\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"448326_heroa\" data-image-description=\"&lt;p&gt;Rooney luchando un bal\u00f3n.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;http:\/\/static.goal.com\/&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&amp;ssl=1\" class=\"size-full wp-image-4407\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?resize=594%2C421\" alt=\"http:\/\/static.goal.com\/\" width=\"594\" height=\"421\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?w=594&amp;ssl=1 594w, https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?resize=75%2C52&amp;ssl=1 75w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a><figcaption id=\"caption-attachment-4407\" class=\"wp-caption-text\">http:\/\/static.goal.com\/<\/figcaption><\/figure>\n<p style=\"text-align: left\">Nueve de cada diez aficionados dir\u00edan que a un equipo con figuras de la talla de De Gea, Herrera, Rooney, Mata o Van Persie la exigencia m\u00ednima es clasificarse, al menos, para competici\u00f3n europea, que aunque sea Europa League siempre da cierto prestigio. Pero cinco tipos, con una calidad incre\u00edble, eso si, no conforman un equipo solvente en partidos trabados, ni garantizan los tres puntos de cada domingo. No hay forma de pretender un equipo serio y competitivo con los Smalling, Valencia, Welbeck, Young, Jones (quiz\u00e1 el \u00fanico defensa, Evra aparte, que aport\u00f3 algo bueno a la zaga el a\u00f1o pasado), Rafael, Evans, Cleverley o Chicharito. El United no solo necesita una profunda reestructuraci\u00f3n en cuanto al episodio de altas y bajas. Necesita centrales de garant\u00edas, pues Marcos Rojo, a pesar de su buena actuaci\u00f3n en el Mundial, no deja de ser lateral, y esa posici\u00f3n estar\u00e1 ocupada durante muchos a\u00f1os por Shaw. Es imposible para un club candidato a todo aspirar siquiera a la Capital One Cup si no tiene seguridad atras, y a d\u00eda de hoy Jones y Evans no la ofrecen.<\/p>\n<p style=\"text-align: left\">La incorporaci\u00f3n de Di Mar\u00eda solventar\u00e1 muchos problemas de transici\u00f3n defensa-ataque, no as\u00ed del modo contrario, pues \u00c1ngel, que ya sabemos que corre por tres, no puede hacerlo por medio equipo, por lo que, como se ha comentado antes, lo imprescindible en estos cuatro d\u00edas de mercado ser\u00e1 fichar defensas de talla mundial, y a pesar de que la n\u00f3mina de los mismos es bastante baja, Louis siempre supo buscar y encontrar. En la zona de creaci\u00f3n, es vital encontrar a un jugador con perfil de Tour\u00e9, un todoterreno que abarque mucho campo, con buena pegada, calidad t\u00e9cnica, excelente lectura t\u00e1ctica y poder\u00edo f\u00edsico. Se estuvo hablando de que el chileno de la Juventus, Arturo Vidal, fichar\u00eda por los diablos rojos en este mercado veraniego, pero parece que se qued\u00f3 en mera especulaci\u00f3n a pesar de que parec\u00eda un claro sustituto en la labor de un Carrick con mucha carga de partidos durante muchos a\u00f1os y que no ha terminado de entenderse con otro buen fichaje del holand\u00e9s, Ander Herrera. La incorporaci\u00f3n de Vidal eximir\u00eda de responsabilidades de mediocentro a Rooney, que se dedicar\u00eda exclusivamente a la labor en la delantera, acompa\u00f1ando a Van Persie.<\/p>\n<p style=\"text-align: left\">Para el 3-5-2 propuesto por Van Gaal los tres centrales han de ser de much\u00edsima garant\u00eda, con buen juego por alto y rapidez al corte, pero el mediocampo requerir\u00e1 una gran velocidad en la fluidez de bal\u00f3n que, actualmente, no tiene. La realidad es que el United necesita consolidarse a nivel colectivo y sumar caras nuevas para un proyecto a largo plazo, establecer un sistema de presi\u00f3n alta y recuperaci\u00f3n para evitar problemas a la contra. Es cierto que estamos a comienzo de temporada, pero se antoja un milagro que el United pueda competir por la Premier en el primer a\u00f1o de la era Van Gaal. Por lo pronto, Europa es el camino que debe volver a tomar para generar ilusi\u00f3n en las gradas de Old Trafford.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mucho se ha escrito sobre el p\u00e9simo inicio de temporada que est\u00e1 firmando el Manchester United, que en tres partidos aun no ha conocido la victoria, a saber: derrota contra el Swansea, empate contra el Sunderland y una brutal paliza propinada por un equipo de League One como es el MK Dons en la ronda&#8230;<\/p>\n","protected":false},"author":343,"featured_media":4407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1371,1368,10],"tags":[29,88,1541,123,1540],"class_list":["post-4405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premier-league-futbol-ingles","category-ligas-mundo","category-portada","tag-di-maria","tag-manchester-united","tag-rojo","tag-rooney","tag-shaw"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salir del infierno. &#8211; Futbolandia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salir del infierno. &#8211; Futbolandia\" \/>\n<meta property=\"og:description\" content=\"Mucho se ha escrito sobre el p\u00e9simo inicio de temporada que est\u00e1 firmando el Manchester United, que en tres partidos aun no ha conocido la victoria, a saber: derrota contra el Swansea, empate contra el Sunderland y una brutal paliza propinada por un equipo de League One como es el MK Dons en la ronda...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/\" \/>\n<meta property=\"og:site_name\" content=\"Futbolandia\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-27T10:53:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-08-27T10:54:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"594\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Josu\u00e9 Rubio Marroqu\u00edn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josu\u00e9 Rubio Marroqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/\"},\"author\":{\"name\":\"Josu\u00e9 Rubio Marroqu\u00edn\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/a9ab41d991f9638593c8936784ad4763\"},\"headline\":\"Salir del infierno.\",\"datePublished\":\"2014-08-27T10:53:16+00:00\",\"dateModified\":\"2014-08-27T10:54:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/\"},\"wordCount\":712,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2014\\\/08\\\/448326_heroa.jpg?fit=594%2C421&ssl=1\",\"keywords\":[\"Di Maria\",\"Manchester United\",\"Rojo\",\"rooney\",\"Shaw\"],\"articleSection\":[\"Barcklays Premier League - F\u00fatbol ingl\u00e9s\",\"Ligas del Mundo\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/\",\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/\",\"name\":\"Salir del infierno. &#8211; Futbolandia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2014\\\/08\\\/448326_heroa.jpg?fit=594%2C421&ssl=1\",\"datePublished\":\"2014-08-27T10:53:16+00:00\",\"dateModified\":\"2014-08-27T10:54:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/a9ab41d991f9638593c8936784ad4763\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2014\\\/08\\\/448326_heroa.jpg?fit=594%2C421&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2014\\\/08\\\/448326_heroa.jpg?fit=594%2C421&ssl=1\",\"width\":594,\"height\":421,\"caption\":\"http:\\\/\\\/static.goal.com\\\/\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/salir-del-infierno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salir del infierno.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#website\",\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/\",\"name\":\"Futbolandia\",\"description\":\"Reportajes e informaci\u00f3n sobre f\u00fatbol mundial y j\u00f3venes promesas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/a9ab41d991f9638593c8936784ad4763\",\"name\":\"Josu\u00e9 Rubio Marroqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g\",\"caption\":\"Josu\u00e9 Rubio Marroqu\u00edn\"},\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/author\\\/ryugarato\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salir del infierno. &#8211; Futbolandia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/","og_locale":"es_ES","og_type":"article","og_title":"Salir del infierno. &#8211; Futbolandia","og_description":"Mucho se ha escrito sobre el p\u00e9simo inicio de temporada que est\u00e1 firmando el Manchester United, que en tres partidos aun no ha conocido la victoria, a saber: derrota contra el Swansea, empate contra el Sunderland y una brutal paliza propinada por un equipo de League One como es el MK Dons en la ronda...","og_url":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/","og_site_name":"Futbolandia","article_published_time":"2014-08-27T10:53:16+00:00","article_modified_time":"2014-08-27T10:54:21+00:00","og_image":[{"width":594,"height":421,"url":"https:\/\/i1.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","type":"image\/jpeg"}],"author":"Josu\u00e9 Rubio Marroqu\u00edn","twitter_misc":{"Escrito por":"Josu\u00e9 Rubio Marroqu\u00edn","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#article","isPartOf":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/"},"author":{"name":"Josu\u00e9 Rubio Marroqu\u00edn","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/a9ab41d991f9638593c8936784ad4763"},"headline":"Salir del infierno.","datePublished":"2014-08-27T10:53:16+00:00","dateModified":"2014-08-27T10:54:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/"},"wordCount":712,"commentCount":0,"image":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","keywords":["Di Maria","Manchester United","Rojo","rooney","Shaw"],"articleSection":["Barcklays Premier League - F\u00fatbol ingl\u00e9s","Ligas del Mundo","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/","url":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/","name":"Salir del infierno. &#8211; Futbolandia","isPartOf":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#primaryimage"},"image":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","datePublished":"2014-08-27T10:53:16+00:00","dateModified":"2014-08-27T10:54:21+00:00","author":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/a9ab41d991f9638593c8936784ad4763"},"breadcrumb":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#primaryimage","url":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","width":594,"height":421,"caption":"http:\/\/static.goal.com\/"},{"@type":"BreadcrumbList","@id":"https:\/\/www.manquepierda.com\/futbolandia\/salir-del-infierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manquepierda.com\/futbolandia\/"},{"@type":"ListItem","position":2,"name":"Salir del infierno."}]},{"@type":"WebSite","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#website","url":"https:\/\/www.manquepierda.com\/futbolandia\/","name":"Futbolandia","description":"Reportajes e informaci\u00f3n sobre f\u00fatbol mundial y j\u00f3venes promesas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manquepierda.com\/futbolandia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/a9ab41d991f9638593c8936784ad4763","name":"Josu\u00e9 Rubio Marroqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/346ca21add48a53f2fa07f696b11c3fa4449f63820250f1038d7a9e1d9abbfb7?s=96&d=mm&r=g","caption":"Josu\u00e9 Rubio Marroqu\u00edn"},"url":"https:\/\/www.manquepierda.com\/futbolandia\/author\/ryugarato\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2014\/08\/448326_heroa.jpg?fit=594%2C421&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p1THIg-193","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts\/4405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/users\/343"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/comments?post=4405"}],"version-history":[{"count":0,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts\/4405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/media\/4407"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/media?parent=4405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/categories?post=4405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/tags?post=4405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}