{"id":876,"date":"2012-02-16T17:42:08","date_gmt":"2012-02-16T15:42:08","guid":{"rendered":"http:\/\/www.manquepierda.com\/futbolandia\/?p=876"},"modified":"2013-07-07T19:05:36","modified_gmt":"2013-07-07T17:05:36","slug":"analisis-champions-league-octavos-de-final-por-javier-gonzalez","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/","title":{"rendered":"An\u00e1lisis Champions League: Octavos de Final"},"content":{"rendered":"<p style=\"text-align: justify\">Interesante jornada la de esta semana, destaca la goleada del Milan de Allegri y la vuelta a la senda del triunfo del F.C Barcelona en la fria Alemania. Previsible la victoria del Lyon ante el Apoel de Nicosia y entretenido Zenit-Benfica, cuya vuelta prevee ser interesantisimo. A partir de esta semana empiezo a analizar la jornada de Champions y Europa League. Empezamos \u00a1<\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #008000\">Lyon 1-0 Apoel<\/span><\/strong><\/p>\n<figure style=\"width: 585px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" \" alt=\"Alexandre Lacazette (i) celebra con sus compa\u00f1eros el gol que le marc\u00f3 a Apoel.\" src=\"http:\/\/es.f1322.mail.yahoo.com\/ya\/download?mid=1%5f126190%5fADtn%2bFcAALifTz0TjQKqQVd1MGs&amp;pid=2&amp;fid=Inbox&amp;inline=1&amp;appid=YahooMailNeoCL\" width=\"585\" height=\"380\" \/><figcaption class=\"wp-caption-text\">Olympique de Lyon vS APOEL Nicosia &#8211; Foto: UEFA.com<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Olympique Lyonnais dio un gran paso hacia los cuartos de final de la Liga de Campeones al hacer valer su mayor experiencia en la competici\u00f3n imponi\u00e9ndose por la m\u00ednima al APOEL de Nicosia en el partido de ida de octavos. El conjunto franc\u00e9s celebr\u00f3 su victoria n\u00famero cincuenta en la m\u00e1xima competici\u00f3n europea de clubes gracias a un valioso gol de Lacazette, una joven promesa de la cantera lionesa. Mucho va a tener que mejorar el APOEL para poder seguir so\u00f1ando con continuar su aventura, sobre todo en el aspecto\u00a0 ofensivo.<\/p>\n<p style=\"text-align: justify\">El t\u00e9cnico lion\u00e9s, Remi Garde, apost\u00f3 en su once inicial por la experiencia, al alinear a Cris en defensa, y por la prudencia al colocar en solitario en punta a Lisandro, dejando en el banquillo a Gomis. En cuanto al conjunto chipriota no hubo sorpresas. Jovanovic coloc\u00f3 a Sousa, reci\u00e9n fichado en el mercado invernal, detr\u00e1s de A\u00edlton, su principal artillero reci\u00e9n recuperado de una lesi\u00f3n. El \u00fanico gol fue obra de Alexandre Lacazette. La vuelta de los octavos ser\u00e1 el 7 de marzo en Chipre.<\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #008000\">B.Leverkusen 1-3 FCBarcelona<\/span><\/strong><\/p>\n<figure style=\"width: 593px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" alt=\"Alexis S\u00e1nchez marca el segundo gol. Martin Meissner | AP\" src=\"http:\/\/es.f1322.mail.yahoo.com\/ya\/download?mid=1%5f126190%5fADtn%2bFcAALifTz0TjQKqQVd1MGs&amp;pid=3&amp;fid=Inbox&amp;inline=1&amp;appid=YahooMailNeoCL\" width=\"593\" height=\"383\" \/><figcaption class=\"wp-caption-text\">F.C Barcelona vS Bayer Leverkusen &#8211; Foto: UEFA.com<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify\">Vital reencuentro con la victoria del F.C Barcelona, que despues de quedarse a 10 puntos del lider ve la Copa del Rey y la Champions como agua de mayo para volver a tener exitos este a\u00f1o. Al comienzo, el Barcelona\u00a0se encontr\u00f3 con muro planteado por el Leverkusen que tard\u00f3 en superar y que hizo que hubiera un primer tiempo con pocas jugadas de ataque. La segunda parte\u00a0fue completamente distinta, con un f\u00fatbol ofensivo de parte de ambos equipos. La apuesta del Leverkusen<strong>\u00a0<\/strong>era clara y todo su planteamiento estaba dirigido a tratar de no dejar jugar al Barcelona. El equipo de Robin Dutt, lleno de respeto por el rival, prefer\u00eda renunciar a posibles situaciones de contragolpe con tal de no perder el orden defensivo y se concentraba en reducirle espacios al contrario a partir de la l\u00ednea central. El Barcelona ten\u00eda una posesi\u00f3n de pelota en torno al 80%, hac\u00eda circular el bal\u00f3n y esperaba que se abrieran posibles boquetes en la muralla que hab\u00eda planteado el Leverkusen.<\/p>\n<p style=\"text-align: justify\">El Leverkusen decidi\u00f3 intentar jugar al f\u00fatbol y pronto se advirti\u00f3 que el Barcelona pod\u00eda ser vulnerable. En el minuto 51 se produjo la primera llegada clara del equipo local con un cabezazo del lateral izquierdo Michael Kadlec al final de una jugada en la que el Barcelona hab\u00eda procurado, sin \u00e9xito, alejar repetidamente la pelota de su \u00e1rea. El Barcelona reaccion\u00f3 de inmediato y otra vez fue la misma f\u00f3rmula la que le devolvi\u00f3 la ventaja. Pase de Cesc por el callej\u00f3n que dejaba abierta la defensa del Barcelona y Alexis que define ante Leno. 1-3 y la eliminatoria casi finiquitada.<\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #008000\">Zenit 3-2 Benfica<\/span><\/strong><\/p>\n<figure style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"http:\/\/es.f1322.mail.yahoo.com\/ya\/download?mid=1%5f126190%5fADtn%2bFcAALifTz0TjQKqQVd1MGs&amp;pid=4&amp;fid=Inbox&amp;inline=1&amp;appid=YahooMailNeoCL\" width=\"600\" height=\"337\" \/><figcaption class=\"wp-caption-text\">Zenit vS Benfica &#8211; Foto: UEFA.com<\/figcaption><\/figure>\n<p style=\"text-align: justify\">El Zenit San Petersburgo derrot\u00f3 al Benfica (3-2) en un partido de los que hacen afici\u00f3n disputado bajo unas condiciones extremas por las g\u00e9lidas temperaturas y el penoso estado del terreno de juego, impropio de una Liga de Campeones. Los portugueses se fajaron muy bien en la primera parte, pero perdieron fuelle seg\u00fan avanzaron los minutos en la segunda parte, lo que fue aprovechado por el equipo ruso para remontar y llevarse la victoria.Como era de esperar, el campo se encontraba en muy mal estado debido al intenso fr\u00edo que sacudi\u00f3 la antigua ciudad imperial rusa durante las \u00faltimas semanas y que estuvieron a punto de causar el aplazamiento del partido.<\/p>\n<p style=\"text-align: justify\">De hecho, el encuentro transcurri\u00f3 con una temperatura que lleg\u00f3 a alcanzar los 13 grados bajo cero, lo que no impidi\u00f3 que los jugadores se dejaran la vida y el estadio Petrovsky mostrara un lleno absoluto. Pese a la dificultad para dar dos pases seguidos con precisi\u00f3n, los portugueses aguantaron muy bien el tipo, mientras el Zenit ech\u00f3 mucho de menos a su mejor jugador, el internacional luso Danny, lesionado de gravedad. Los primeros minutos no dejaron ninguna oportunidad de peligro y, de hecho, la primera ocasi\u00f3n de la que dispusieron ambos equipos acab\u00f3 en gol. 3-2 y la vuelta en Portugal con la eliminatoria en el aire, promete emocion hasta el final.<\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #008000\">Milan 4-0 Arsenal<\/span><\/strong><\/p>\n<figure style=\"width: 590px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" alt=\"Stage Image\" src=\"http:\/\/es.f1322.mail.yahoo.com\/ya\/download?mid=1%5f126190%5fADtn%2bFcAALifTz0TjQKqQVd1MGs&amp;pid=5&amp;fid=Inbox&amp;inline=1&amp;appid=YahooMailNeoCL\" width=\"590\" height=\"395\" \/><figcaption class=\"wp-caption-text\">Milan vS Arsenal &#8211; Foto: UEFA.com<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify\">El Mil\u00e1n se impuso al Arsenal en la ida de los octavos de final de la Liga de Campeones con un rotundo 4-0, una victoria con la que el equipo italiano sepulta pr\u00e1cticamente su \u00abmaldici\u00f3n inglesa\u00bb y que propici\u00f3 la gran actuaci\u00f3n del brasile\u00f1o Robinho y del sueco Zlatan Ibrahimovic. De hecho, Robinho logr\u00f3 un &#8216;doblete&#8217; en una g\u00e9lida noche en el Estadio \u00abGiuseppe Meazza\u00bb (San Siro), donde los aficionados del Mil\u00e1n celebraron una victoria con la que acarician ya su deseo de romper la racha de tres eliminaciones en octavos de Liga de Campeones a manos de equipos ingleses en los \u00faltimos a\u00f1os. Los hombres del t\u00e9cnico italiano Massimiliano Allegri, que comenzaron adelant\u00e1ndose en el marcador con un espl\u00e9ndido gol del ghan\u00e9s de origen alem\u00e1n Kevin-Prince Boateng, consiguieron bloquear el juego del Arsenal y dar un importante paso hacia la venganza de su eliminaci\u00f3n en 2008 a cargo de los \u00abgunners\u00bb.<\/p>\n<p style=\"text-align: justify\">El que \u00aba priori\u00bb se planteaba como un duelo directo entre Ibrahimovic y el delantero del Arsenal Robin Van Persie, termin\u00f3 decant\u00e1ndose del lado del sueco, ya no solo por el tanto de penalti que logr\u00f3, sino tambi\u00e9n por sus asistencias, nada que ver con el capit\u00e1n holand\u00e9s del equipo ingl\u00e9s, casi desaparecido hoy. La primera mitad del encuentro fue de un absoluto dominio del vigente campe\u00f3n de la Liga italiana, salvo en los minutos que transcurrieron entre el primer y el segundo gol, donde los hombres del t\u00e9cnico franc\u00e9s Ars\u00e8ne Wenger consiguieron llegar a porter\u00eda, aunque sin mucho peligro. El partido comenz\u00f3 con el franc\u00e9s Thierry Henry en el banquillo y con la tempranera sustituci\u00f3n del capit\u00e1n del Mil\u00e1n, el holand\u00e9s Clarence Seedorf, quien acus\u00f3 molestias y tuvo que ser reemplazado en el minuto 12 del encuentro por su compatriota Urby Emanuelson. Solo tres minutos despu\u00e9s llegar\u00eda el primer tanto de los \u00abrossoneri\u00bb en las botas de Boateng con un gran control de pecho tras el que engancha una volea que lleva el bal\u00f3n a la red con la ayuda del travesa\u00f1o. 4-0 y la eliminatoria sentenciada, resultado sorprendente no por la victoria, sino por lo abultado del marcador, otro a\u00f1o en el que Arsene Wenger y sus pupilos se quedan fuera prematuramente.<\/p>\n<p style=\"text-align: justify\">Javier Gonzalez<\/p>\n<p style=\"text-align: justify\">@JaviRbetis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interesante jornada la de esta semana, destaca la goleada del Milan de Allegri y la vuelta a la senda del triunfo del F.C Barcelona en la fria Alemania. Previsible la victoria del Lyon ante el Apoel de Nicosia y entretenido Zenit-Benfica, cuya vuelta prevee ser interesantisimo. A partir de esta semana empiezo a analizar la&#8230;<\/p>\n","protected":false},"author":100,"featured_media":887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,10],"tags":[442,398,454],"class_list":["post-876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mas-futbol","category-portada","tag-analisis","tag-champions","tag-league"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia\" \/>\n<meta property=\"og:description\" content=\"Interesante jornada la de esta semana, destaca la goleada del Milan de Allegri y la vuelta a la senda del triunfo del F.C Barcelona en la fria Alemania. Previsible la victoria del Lyon ante el Apoel de Nicosia y entretenido Zenit-Benfica, cuya vuelta prevee ser interesantisimo. A partir de esta semana empiezo a analizar la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/\" \/>\n<meta property=\"og:site_name\" content=\"Futbolandia\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-16T15:42:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-07-07T17:05:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"358\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adri\u00e1n Bedia Puerto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adri\u00e1n Bedia Puerto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/\"},\"author\":{\"name\":\"Adri\u00e1n Bedia Puerto\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/f2133132be9857df14a26e2f116bbe94\"},\"headline\":\"An\u00e1lisis Champions League: Octavos de Final\",\"datePublished\":\"2012-02-16T15:42:08+00:00\",\"dateModified\":\"2013-07-07T17:05:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/\"},\"wordCount\":1247,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2012\\\/02\\\/153999hp2.jpg?fit=560%2C358&ssl=1\",\"keywords\":[\"Analisis\",\"Champions\",\"League\"],\"articleSection\":[\"Mas f\u00fatbol\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/\",\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/\",\"name\":\"An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2012\\\/02\\\/153999hp2.jpg?fit=560%2C358&ssl=1\",\"datePublished\":\"2012-02-16T15:42:08+00:00\",\"dateModified\":\"2013-07-07T17:05:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/f2133132be9857df14a26e2f116bbe94\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2012\\\/02\\\/153999hp2.jpg?fit=560%2C358&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.manquepierda.com\\\/futbolandia\\\/files\\\/2012\\\/02\\\/153999hp2.jpg?fit=560%2C358&ssl=1\",\"width\":\"560\",\"height\":\"358\",\"caption\":\"Foto: Futbolete.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lisis Champions League: Octavos de Final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#website\",\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/\",\"name\":\"Futbolandia\",\"description\":\"Reportajes e informaci\u00f3n sobre f\u00fatbol mundial y j\u00f3venes promesas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/#\\\/schema\\\/person\\\/f2133132be9857df14a26e2f116bbe94\",\"name\":\"Adri\u00e1n Bedia Puerto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g\",\"caption\":\"Adri\u00e1n Bedia Puerto\"},\"sameAs\":[\"http:\\\/\\\/minimessisyzidanes.blogspot.com\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/twitter.com\\\/Abp1993\"],\"url\":\"https:\\\/\\\/www.manquepierda.com\\\/futbolandia\\\/author\\\/abp1993\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia","og_description":"Interesante jornada la de esta semana, destaca la goleada del Milan de Allegri y la vuelta a la senda del triunfo del F.C Barcelona en la fria Alemania. Previsible la victoria del Lyon ante el Apoel de Nicosia y entretenido Zenit-Benfica, cuya vuelta prevee ser interesantisimo. A partir de esta semana empiezo a analizar la...","og_url":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/","og_site_name":"Futbolandia","article_published_time":"2012-02-16T15:42:08+00:00","article_modified_time":"2013-07-07T17:05:36+00:00","og_image":[{"width":560,"height":358,"url":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","type":"image\/jpeg"}],"author":"Adri\u00e1n Bedia Puerto","twitter_misc":{"Escrito por":"Adri\u00e1n Bedia Puerto","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#article","isPartOf":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/"},"author":{"name":"Adri\u00e1n Bedia Puerto","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/f2133132be9857df14a26e2f116bbe94"},"headline":"An\u00e1lisis Champions League: Octavos de Final","datePublished":"2012-02-16T15:42:08+00:00","dateModified":"2013-07-07T17:05:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/"},"wordCount":1247,"commentCount":0,"image":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","keywords":["Analisis","Champions","League"],"articleSection":["Mas f\u00fatbol","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/","url":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/","name":"An\u00e1lisis Champions League: Octavos de Final &#8211; Futbolandia","isPartOf":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#primaryimage"},"image":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","datePublished":"2012-02-16T15:42:08+00:00","dateModified":"2013-07-07T17:05:36+00:00","author":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/f2133132be9857df14a26e2f116bbe94"},"breadcrumb":{"@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#primaryimage","url":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","width":"560","height":"358","caption":"Foto: Futbolete.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.manquepierda.com\/futbolandia\/analisis-champions-league-octavos-de-final-por-javier-gonzalez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manquepierda.com\/futbolandia\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lisis Champions League: Octavos de Final"}]},{"@type":"WebSite","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#website","url":"https:\/\/www.manquepierda.com\/futbolandia\/","name":"Futbolandia","description":"Reportajes e informaci\u00f3n sobre f\u00fatbol mundial y j\u00f3venes promesas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manquepierda.com\/futbolandia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manquepierda.com\/futbolandia\/#\/schema\/person\/f2133132be9857df14a26e2f116bbe94","name":"Adri\u00e1n Bedia Puerto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dea43547063ac034552de9ba24b2ce5dd1cf7bf2de4f05263cfbf331d51d3c5c?s=96&d=mm&r=g","caption":"Adri\u00e1n Bedia Puerto"},"sameAs":["http:\/\/minimessisyzidanes.blogspot.com","https:\/\/x.com\/http:\/\/twitter.com\/Abp1993"],"url":"https:\/\/www.manquepierda.com\/futbolandia\/author\/abp1993\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/futbolandia\/files\/2012\/02\/153999hp2.jpg?fit=560%2C358&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p1THIg-e8","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts\/876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/comments?post=876"}],"version-history":[{"count":0,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/posts\/876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/media\/887"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/media?parent=876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/categories?post=876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/futbolandia\/wp-json\/wp\/v2\/tags?post=876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}