{"id":40820,"date":"2015-02-02T12:39:46","date_gmt":"2015-02-02T11:39:46","guid":{"rendered":"http:\/\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg"},"modified":"2015-02-02T12:40:04","modified_gmt":"2015-02-02T11:40:04","slug":"patrickjosephoconnell-25","status":"inherit","type":"attachment","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/1935-febrero-03-nervion-sevilla-fc-0-real-betis-balompie-3-80aniversario-datos-estadisticos\/patrickjosephoconnell-25\/","title":{"rendered":"PatrickJosephO&#8217;CONNELL"},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"class_list":["post-40820","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a1ij08-aCo","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"343\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?fit=206%2C343&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?w=206&amp;ssl=1 206w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?resize=132%2C220&amp;ssl=1 132w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>MMMMM<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":206,"height":343,"file":"2015\/02\/PatrickJosephOCONNELL.jpg","sizes":{"thumbnail":{"file":"PatrickJosephOCONNELL-132x220.jpg","width":132,"height":220,"wp_smushit":"Reduced by 7.7% (900&nbsp;B)","mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?fit=132%2C220&ssl=1"},"full":{"file":"PatrickJosephOCONNELL.jpg?fit=206%2C343&ssl=1","width":206,"height":343,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg?fit=206%2C343&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"wp_smushit":"Reduced by 7.0% (3.1&nbsp;KB)"},"post":40806,"source_url":"https:\/\/www.manquepierda.com\/historiarealbetis\/files\/2015\/02\/PatrickJosephOCONNELL.jpg","_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/40820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=40820"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":40806,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/40806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}