{"id":102367,"date":"2025-03-17T11:00:00","date_gmt":"2025-03-17T10:00:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=102367"},"modified":"2025-03-11T08:02:39","modified_gmt":"2025-03-11T07:02:39","slug":"entrevista-jose-ramon-esnaola-1995","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/entrevista-jose-ramon-esnaola-1995\/","title":{"rendered":"Entrevista Jos\u00e9 Ram\u00f3n Esnaola 1995."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"700\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=467%2C700&#038;ssl=1\" alt=\"\" class=\"wp-image-102368\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=467%2C700&amp;ssl=1 467w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=147%2C220&amp;ssl=1 147w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?w=1560&amp;ssl=1 1560w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/figure>\n<\/div>\n\n<p>\u00a0<\/p>\n<p>Jos\u00e9 Ram\u00f3n Esnaola se hizo cargo del filial b\u00e9tico entre las temporadas 1989-90 y 1991-92, con una breve incursi\u00f3n en la direcci\u00f3n del primer equipo en 1991. Antes, desde 1986, hab\u00eda estado al cargo de los juveniles, adem\u00e1s de ser el segundo de entrenadores del primer equipo como John Mortimore o Eusebio R\u00edos.<\/p>\n<p>En la temporada 1992-93 volvi\u00f3 a dirigir al equipo juvenil, aunque desde marzo de 1993 volvi\u00f3 a hacerse cargo del primer equipo hasta final de temporada.\u00a0<\/p>\n<p>En la campa\u00f1a 1993-94 tom\u00f3 de nuevo la direcci\u00f3n del filial, con el que se proclam\u00f3 campe\u00f3n en Tercera Divisi\u00f3n y logr\u00f3 el ascenso a Segunda B en la liguilla final.<\/p>\n<p>En la campa\u00f1a 1994-95, con un equipo muy joven y renovado, logr\u00f3 mantener al equipo de forma holgada en la categor\u00eda de bronce del f\u00fatbol.<\/p>\n<p>Esta entrevista, del mes de abril de 1995, y a cargo de Inmaculada Carmona en las p\u00e1ginas de Diario 16 Andaluc\u00eda, recoge las sensaciones del t\u00e9cnico guipuzcoano, que dirigir\u00eda al Betis B de forma ininterrumpida hasta la campa\u00f1a 1999-00.<\/p>\n<p><span style=\"color: #008000\"><em>El filial b\u00e9tico, pese al joven e inexperto equipo que ha puesto en liza, se ha ido adaptando paulatinamente a la categor\u00eda y est\u00e9 realizando una magn\u00edfica campa\u00f1a. El domingo, con su triunfo en San Fernando, qued\u00f3 limpio de negativos, con lo que asegura su posici\u00f3n ante la visita del C\u00f3rdoba, l\u00edder destacado del grupo.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>Al respecto, nos dice Esnaola:<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>El trabajo que estamos realizando va dando sus frutos, el equipo mejora poco a poco y es importante, despu\u00e9s de esta victoria, poder recibir al C\u00f3rdoba limpio de negativos<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>Es muy probable que Esnaola hubiera firmado al principio la actual posici\u00f3n de su equipo\u2014und\u00e9cimo, con 30 puntos\u2014lo que pocos esperaban en la pretemporada.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Nunca se sabe, pero de todas formas, lo ve\u00eda muy complicado. Se hizo una plantilla nueva, se tuvo que acoplar a los jugadores a una categor\u00eda muy dif\u00edcil, y hubo que esperar a que el equipo fuera super\u00e1ndose para que termine haciendo una buena campa\u00f1a<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>Sin embargo, de no perder algunos puntos por inexperiencia o mala suerte, el equipo b\u00e9tico podr\u00eda estar ahora cerca de los puestos de play off:<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Creo que el equipo ha trabajado muy bien y con ilusi\u00f3n; se han perdido muchos puntos jugando casi todos los partidos locales lejos del estadio, lo que da ventaja a los rivales. No obstante, estar arriba es dif\u00edcil, pues siempre se pierden puntos en casa<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>En el f\u00fatbol, lo que cuentan son los resultados, por lo que hay que preguntar a Jos\u00e9 Ram\u00f3n Esnaola si cree que los aficionados valoran la trayectoria que est\u00e1 manteniendo su equipo pese a su juventud:<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Yo creo que con el tiempo terminan d\u00e1ndose cuenta de lo que hay. Todos saben que disminuy\u00f3 la cantera y ahora es m\u00e1s dif\u00edcil confeccionar un equipo para Segunda B, pero tanto la afici\u00f3n como la directiva saben que mantenerse ya es un \u00e9xito, aparte de que algunos jugadores suban al primer equipo, donde Quico ya ha jugado esta temporada<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>Sobre que el club haya aumentado a cuatro sus equipos de cantera, opina Esnaola:<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Se suprimi\u00f3 el sub 19 porque era muy costoso, pero me imagino que despu\u00e9s de que el primer equipo, con seis o siete jugadores de la casa, se haya consolidado en Primera, la directiva piensa que la cantera es rentable, por lo que seguir\u00e1 aumentando para sacar el m\u00e1ximo provecho<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>El trabajo de Esnaola esta temporada ha sido arduo y lo que m\u00e1s le ha recalcado a sus j\u00f3venes jugadores ha sido que \u201csi la pasada temporada hicimos una buena campa\u00f1a en Tercera, en \u00e9sta podr\u00edamos mantenernos con dignidad en Segunda B, as\u00ed como que si el primer equipo tiene veinte jugadores, si ellos destacan, podr\u00edan ocupar algunos de esos lugares\u201d.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>De los \u00faltimos partidos a domicilio el filial b\u00e9tico s\u00f3lo ha perdido dos, lo que demuestra que pese a su juventud le ha tomado el pulso a la categor\u00eda.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Eso\u2014recalca Esnaola\u2014nos ha permitido jugar con m\u00e1s tranquilidad y realizar el juego que nos conviene<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>Precisamente esa racha se inici\u00f3 tras la visita del C\u00f3rdoba, el pr\u00f3ximo rival del conjunto b\u00e9tico.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>As\u00ed es, ha transcurrido una vuelta entera. All\u00ed perdimos por 3-0 y nos vimos en una situaci\u00f3n inc\u00f3moda, pero el equipo se mentaliz\u00f3, se sobrepuso, juega muy bien fuera y esperamos que la racha dure<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>Lo m\u00e1s positivo y negativo del equipo para Esnaola es \u201cla ilusi\u00f3n que ponen los chavales por llegar al primer equipo y lo dif\u00edcil que cuesta hacer ahora un equipo por la reducida cantera que tenemos\u201d.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Ganar el domingo en San Fernando ha sido satisfactorio, porque podremos recibir al C\u00f3rdoba limpio de negativos, lo que era fundamental, y lo m\u00e1s decepcionante, perder en los \u00faltimos minutos con Sevilla B, San Roque y C\u00e1diz, ante \u00e9ste despu\u00e9s de ir ganando 0-1<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>La lucha por el play off de ascenso est\u00e1 en su apogeo, aunque es el cuarto puesto, tras el frenazo del Almer\u00eda CF, el que anda m\u00e1s disputado. A falta de ocho jornadas, Esnaola apuesta por \u201cC\u00f3rdoba, \u00c9cija y Sevilla B, mientras que el por cuarto puesto pelear\u00e1n cuatro o cinco equipos, entre los que figuran Almer\u00eda CF, Yeclano, Talavera y Ja\u00e9n\u201d. \u00a0<\/em><\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Jos\u00e9 Ram\u00f3n Esnaola se hizo cargo del filial b\u00e9tico entre las temporadas 1989-90 y 1991-92, con una breve incursi\u00f3n en la direcci\u00f3n del primer equipo en 1991. Antes, desde 1986, hab\u00eda estado al cargo de los juveniles, adem\u00e1s de ser el segundo de entrenadores del primer equipo como John Mortimore o Eusebio R\u00edos. En&#8230;<\/p>\n","protected":false},"author":5,"featured_media":102368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[905,17191,892,1],"tags":[2460,2459,1302,17908,17394],"class_list":["post-102367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1990-1999","category-cantera","category-entrenadores-temas","category-portada","tag-1994-95","tag-2459","tag-jose-ramon-esnaola","tag-liga-segunda-b-1994-95","tag-real-betis-balompie-b"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-qD5","jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/03\/Entrevista-Jose-Ramon-Esnaola-1995.jpg?fit=1560%2C2340&ssl=1","_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/102367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=102367"}],"version-history":[{"count":2,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/102367\/revisions"}],"predecessor-version":[{"id":102370,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/102367\/revisions\/102370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/102368"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=102367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=102367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=102367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}