{"id":104646,"date":"2025-09-24T13:00:00","date_gmt":"2025-09-24T11:00:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=104646"},"modified":"2025-08-25T10:34:51","modified_gmt":"2025-08-25T08:34:51","slug":"hoy-hace-75-anos-utrera-3-betis-3","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/hoy-hace-75-anos-utrera-3-betis-3\/","title":{"rendered":"Hoy hace 75 a\u00f1os. Utrera 3 Betis 3."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"632\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?resize=960%2C632&#038;ssl=1\" alt=\"\" class=\"wp-image-104647\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?resize=960%2C632&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?resize=680%2C447&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?resize=220%2C145&amp;ssl=1 220w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?resize=768%2C505&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?w=971&amp;ssl=1 971w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/div>\n\n<p>\u00a0<\/p>\n<p><span style=\"color: #008000\">El 24 de septiembre de 1950 en San Juan Bosco Utrera y Betis empatan a 3 en partido de la jornada 3 del Campeonato de Liga de Tercera Divisi\u00f3n.<\/span><\/p>\n<p><span style=\"color: #008000\">Dom\u00ednguez en el minuto 6, a pase de Gelo, adelant\u00f3 al Betis; en el 24 empat\u00f3 el Utrera con un remate de Ruiz a centro de Pastor. En el 30 Gelo, tras un fallo del guardameta local, hizo el 1-2 con el que concluy\u00f3 la primera parte.<\/span><\/p>\n<p><span style=\"color: #008000\">En el 55 Ruiz de cabeza hizo el 2-2, que deshizo Dom\u00ednguez para el Betis en el 65 tras una jugada de Eduardito. El Utrera volvi\u00f3 a empatar en el 78, de nuevo por mediaci\u00f3n de Ruiz.<\/span><\/p>\n<p><span style=\"color: #008000\">El Utrera, entrenado por Joaqu\u00edn Pacheco, form\u00f3 con Guti\u00e9rrez; Jim\u00e9nez, Alonso, Guillam\u00f3n; Aumesquet, Pedrito; Ruiz, Lis, Ruiz, Troncoso y Pastor.<\/span><\/p>\n<p><span style=\"color: #008000\">El Betis, dirigido por Andr\u00e9s Aranda, aline\u00f3 a Ibarra; M\u00e1ximo, F\u00e9lix, Utrilla; Paquirrini, Esteban; Gelo, Patricio, Dom\u00ednguez, Regatero y Eduardito.<\/span><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 El 24 de septiembre de 1950 en San Juan Bosco Utrera y Betis empatan a 3 en partido de la jornada 3 del Campeonato de Liga de Tercera Divisi\u00f3n. Dom\u00ednguez en el minuto 6, a pase de Gelo, adelant\u00f3 al Betis; en el 24 empat\u00f3 el Utrera con un remate de Ruiz a centro&#8230;<\/p>\n","protected":false},"author":5,"featured_media":104647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[901,14583,1],"tags":[2661,4653,17936],"class_list":["post-104646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1950-1959","category-efemerides","category-portada","tag-2661","tag-cd-utrera","tag-liga-tercera-1950-51"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/08\/24-1950-Utrera-3-Betis-3-.jpg?fit=971%2C639&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-rdQ","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/104646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=104646"}],"version-history":[{"count":1,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/104646\/revisions"}],"predecessor-version":[{"id":104648,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/104646\/revisions\/104648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/104647"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=104646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=104646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=104646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}