{"id":105563,"date":"2025-11-04T11:00:00","date_gmt":"2025-11-04T10:00:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=105563"},"modified":"2026-02-10T12:34:36","modified_gmt":"2026-02-10T11:34:36","slug":"ruben-castro","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/ruben-castro\/","title":{"rendered":"Rub\u00e9n Castro."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-105564\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=920%2C920&amp;ssl=1 920w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?w=1737&amp;ssl=1 1737w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n<p><strong>Rub\u00e9n Castro Mart\u00edn<\/strong>, nacido en Las Palmas el 27 de junio de 1981.<\/p>\n<p>Delantero.<\/p>\n<p>Formado en las categor\u00edas inferiores de la UD Las Palmas, jug\u00f3 en el filial grancanario durante 2 temporadas, hasta debutar en el primer equipo en febrero de 2001. Con el equipo canario se proclam\u00f3 m\u00e1ximo goleador de Segunda Divisi\u00f3n en la campa\u00f1a 2003-04.\u00a0<\/p>\n<p>En el verano de 2004 fue traspasado al Deportivo de La Coru\u00f1a, aunque fue cedido al Albacete. De regreso al equipo gallego no logr\u00f3 hacerse con la titularidad en la campa\u00f1a 2005-06, por lo que volvi\u00f3 a ser cedido al Racing de Santander y al N\u00e1stic de Tarragona en la 2006-07. Al a\u00f1o siguiente volvi\u00f3 al Deportivo, aunque tampoco fue titular habitualmente. Huesca y Rayo Vallecano fueron sus siguientes destino como cedido, en 2 campa\u00f1as en las que recuper\u00f3 el olfato goleador.<\/p>\n<p>En el verano de 2010 fich\u00f3 por el Betis, por recomendaci\u00f3n del t\u00e9cnico b\u00e9tico Pepe Mel, con quien hab\u00eda coincidido en el equipo rayista. En su primera campa\u00f1a en el Betis contribuy\u00f3 de forma decisiva con los 27 goles marcados en el ascenso b\u00e9tico a la Primera Divisi\u00f3n.<\/p>\n<p>A lo largo de sus 8 temporadas en el Betis fue el m\u00e1ximo realizador de la plantilla b\u00e9tica en todas las temporadas. Fue adem\u00e1s m\u00e1ximo goleador de Segunda Divisi\u00f3n en la 2014-15 con 32 tantos.<\/p>\n<p>Y se convirti\u00f3 en el m\u00e1ximo goleador hist\u00f3rico del club con 148 tantos en partidos oficiales.\u00a0\u00a0<\/p>\n<p>En la primera parte de la campa\u00f1a 2017-18 fue cedido al conjunto chino del Guizhou, en la Primera Divisi\u00f3n china.\u00a0<\/p>\n<p>Cuando dej\u00f3 el Betis a final de la temporada 2017-18 volvi\u00f3 a Las Palmas, donde jug\u00f3 2 temporadas, pasando posteriormente por Cartagena y M\u00e1laga hasta su retirada en 2023.<\/p>\n<p>Incomprensiblemente nunca jug\u00f3 con la selecci\u00f3n absoluta, aunque s\u00ed lo hizo con la sub 21.<\/p>\n<p>Historial<\/p>\n<table width=\"258\">\n<tbody>\n<tr>\n<td width=\"80\">1999-00<\/td>\n<td width=\"98\">Las Palmas B<\/td>\n<td width=\"80\">Tercera<\/td>\n<\/tr>\n<tr>\n<td>2000-01<\/td>\n<td>Las Palmas B<\/td>\n<td>Tercera<\/td>\n<\/tr>\n<tr>\n<td>2000-01<\/td>\n<td>Las Palmas<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2001-02<\/td>\n<td>Las Palmas<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2002-03<\/td>\n<td>Las Palmas<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2003-04<\/td>\n<td>Las Palmas<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2004-05<\/td>\n<td>Albacete<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2005-06<\/td>\n<td>Deportivo<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2006-07<\/td>\n<td>Racing<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2006-07<\/td>\n<td>Gimnastic<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2007-08<\/td>\n<td>Deportivo<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2008-09<\/td>\n<td>Huesca<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2009-10<\/td>\n<td>Rayo Vallecano<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2010-11<\/td>\n<td>Betis<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2011-12<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2012-13<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2013-14<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2014-15<\/td>\n<td>Betis<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2015-16<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2016-17<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2017-18<\/td>\n<td>Guizhou<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2017-18<\/td>\n<td>Betis<\/td>\n<td>Primera<\/td>\n<\/tr>\n<tr>\n<td>2018-19<\/td>\n<td>Las Palmas<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2019-20<\/td>\n<td>Las Palmas<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2020-21<\/td>\n<td>Cartagena<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2021-22<\/td>\n<td>Cartagena<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<tr>\n<td>2022-23<\/td>\n<td>M\u00e1laga<\/td>\n<td>Segunda<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>En sus 8 temporadas en el Betis Rub\u00e9n Castro jug\u00f3 260 partidos de Liga, marcando 136 goles, 24 de Copa, en los que hizo 10 tantos, 6 en Liga Europa, marcando 2 goles, y\u00a0 62 amistosos, en los que obtuvo 45 goles.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Rub\u00e9n Castro Mart\u00edn, nacido en Las Palmas el 27 de junio de 1981. Delantero. Formado en las categor\u00edas inferiores de la UD Las Palmas, jug\u00f3 en el filial grancanario durante 2 temporadas, hasta debutar en el primer equipo en febrero de 2001. Con el equipo canario se proclam\u00f3 m\u00e1ximo goleador de Segunda Divisi\u00f3n en la&#8230;<\/p>\n","protected":false},"author":5,"featured_media":105564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[893,1],"tags":[748],"class_list":["post-105563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jugadores-temas","category-portada","tag-ruben-castro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/11\/Ruben-Castro.jpg?fit=1737%2C1737&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-rsD","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/105563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=105563"}],"version-history":[{"count":3,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/105563\/revisions"}],"predecessor-version":[{"id":106807,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/105563\/revisions\/106807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/105564"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=105563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=105563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=105563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}