{"id":106181,"date":"2025-12-17T11:00:00","date_gmt":"2025-12-17T10:00:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=106181"},"modified":"2025-12-14T10:59:58","modified_gmt":"2025-12-14T09:59:58","slug":"la-temporada-1965-66","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/la-temporada-1965-66\/","title":{"rendered":"La temporada 1965-66."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"607\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?resize=796%2C607&#038;ssl=1\" alt=\"\" class=\"wp-image-106182\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?w=796&amp;ssl=1 796w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?resize=680%2C519&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?resize=220%2C168&amp;ssl=1 220w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?resize=768%2C586&amp;ssl=1 768w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/><\/figure>\n<\/div>\n\n<p><span style=\"color: #008000;\">El 26 de julio en el Villamar\u00edn comienzan los entrenamientos de la primera plantilla b\u00e9tica. Al frente de ella el t\u00e9cnico brasile\u00f1o Martim Francisco, 37 a\u00f1os,\u00a0 presente en el f\u00fatbol espa\u00f1ol desde 1958 en que entren\u00f3 al Athletic. La campa\u00f1a anterior hab\u00eda dirigido al Elche, al que clasific\u00f3 en 8\u00aa posici\u00f3n.<\/span><\/p>\n<p><span style=\"color: #008000;\">En la plantilla b\u00e9tica se produjeron 10 bajas: Agust\u00edn Asenjo (Indauchu), Jos\u00e9 Casas \u00abPep\u00edn\u00bb (Las Palmas), Andr\u00e9s Molina (Mallorca), Andr\u00e9s Bosch (Sants), Antonio Garrido (cedido al Melilla), Jos\u00e9 L\u00f3pez Hidalgo (Murcia), Jos\u00e9 Breval (cedido al Murcia), Manuel Ordaz (Almer\u00eda), Jos\u00e9 Mar\u00eda Corral (retirado) y Manuel Guerra.<\/span><\/p>\n<p><span style=\"color: #008000;\">Las altas fueron 10: Juan Perea Esteve (Elche), Antonio Cano \u00abZacarizo\u00bb (M\u00e1laga), Fernando Gir\u00f3n (Oviedo), Manuel Vega (tras cesi\u00f3n al Constancia), \u00c1ngel De la Fuente (Murcia), Jes\u00fas Mar\u00eda Landa (Atl\u00e9tico Baleares), Manuel Moreno (Mallorca), Dionisio G\u00f3mez \u00abDioni\u00bb (cantera), Juan Santisteban (Real Madrid) y Juan Cladera (Atl\u00e9tico Baleares).\u00a0 \u00a0<\/span><\/p>\n<p><span style=\"color: #008000;\">Se jugaron 2 amistosos (derrota 3-1 frente al Xerez y victoria 8-1 contra el Portuense), antes de participar en C\u00e1diz en el Trofeo Carranza, donde se defend\u00eda el t\u00edtulo conseguido el a\u00f1o anterior. El resultado no fue bueno, con derrotas 1-2 ante el Benfica en semifinales y 0-3 contra el Flamengo en la consolaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #008000;\">El Betis disput\u00f3 en este temporada 2 competiciones oficiales: el Campeonato de Liga de Primera Divisi\u00f3n y la Copa.<\/span><\/p>\n<p><span style=\"color: #008000;\">La Liga se inici\u00f3 el 5 de septiembre en San Mam\u00e9s frente al Athletic, y finaliz\u00f3 el 3 de abril de 1966 en La Rosaleda contra el M\u00e1laga, un partido dram\u00e1tico con empate a 1, gol local en el minuto 89, que mandaba al equipo a Segunda Divisi\u00f3n, quedando en la posici\u00f3n 16\u00aa con 23 puntos, tras 7 victorias, 9 empates y 14 derrotas, con 36 goles a favor y 60 en contra.<\/span><\/p>\n<p><span style=\"color: #008000;\">En la jornada 12 fue cesado el brasile\u00f1o Martim Francisco, sustituy\u00e9ndole Ernesto Pons, quien por tercera ocasi\u00f3n se hac\u00eda cargo del Betis en las 4 \u00faltimas temporadas.<\/span><\/p>\n<p><span style=\"color: #008000;\">Sin embargo en la Copa, disputada tras finalizar la Liga, la trayectoria b\u00e9tica fue sorprendente, plant\u00e1ndose en semifinales tras eliminar al Oviedo, Espanyol y Real Madrid. En la ida de la semifinal se consigui\u00f3 un empate a 1 en Bilbao, pero en la vuelta el conjunto rojiblanco se impuso 1-4 en Sevilla.<\/span><\/p>\n<p><span style=\"color: #008000;\">En los 38 encuentros oficiales jugados en la temporada (30 de Liga y 8 de Copa) el Betis utiliz\u00f3 un total de 26 futbolistas: Joaqu\u00edn Sierra \u00abQuino\u00bb (32), Rogelio Sosa (30), Antonio Mart\u00ednez \u00abAnt\u00f3n\u00bb (29), Fernando Ansola (29), Jos\u00e9 Mar\u00eda Garc\u00eda \u00abMontaner\u00bb (27), Francisco Grau (25), Eusebio R\u00edos (25), Miguel Azc\u00e1rate (25), Francisco Aparicio (21), Francisco Ortiz \u00abFrasco\u00bb (21), Fernando Gir\u00f3n (16), Juan Perea Esteve (15), Jes\u00fas Mar\u00eda Landa (15), Antonio Pallar\u00e9s (14), Manuel Vega (13), Dionisio G\u00f3mez \u00abDioni\u00bb (13), Antonio Cano \u00abZacarizo\u00bb (13), Agust\u00edn Carmet (10), \u00c1ngel Su\u00e1rez (10), Enrique Mateos (10), \u00c1ngel De la Fuente (8), Manuel Moreno (6), Juan Santisteban (5), Francisco Faleato \u00abPaquito\u00bb (3), Antonio Cruz (2) y Juan Cladera (1).\u00a0<\/span><\/p>\n<p><span style=\"color: #008000;\">Los autores de los goles b\u00e9ticos fueron: Fernando Ansola (12), Joaqu\u00edn Sierra \u00abQuino\u00bb (11), Rogelio Sosa (8), Jes\u00fas Mar\u00eda Landa (5) Francisco Ortiz \u00abFrasco\u00bb (3), Fernando Gir\u00f3n (3), Antonio Pallar\u00e9s (2), Antonio Cano \u00abZacarizo\u00bb (2), Antonio Mart\u00ednez \u00abAnt\u00f3n\u00bb (1), Miguel Azc\u00e1rate (1), Jos\u00e9 Mar\u00eda Garc\u00eda \u00abMontaner\u00bb (1), Juan Santisteban (1), \u00c1ngel De la Fuente (1) y Enrique Mateos (1).<\/span><\/p>\n<p><span style=\"color: #008000;\">Con la selecci\u00f3n absoluta debut\u00f3 Fernando Ansola, mientras que Dioni y Quino lo hicieron con la de aficionados y Rogelio con la sub 23.<\/span><\/p>\n<p><span style=\"color: #008000;\">El Triana Balompi\u00e9, filial b\u00e9tico, entrenado por Rafael Villar\u00edn, milit\u00f3 en el grupo XII de la Tercera Divisi\u00f3n, clasific\u00e1ndose en la 6\u00aa posici\u00f3n, con 30 puntos, tras 9 victorias, 12 empates y 9 derrotas, con 37 goles a favor y 39 en contra.<\/span><\/p>\n<p><span style=\"color: #008000;\">El gran \u00e9xito del Triana Balompi\u00e9 fue su triunfo en la Copa S\u00e1nchez Pizju\u00e1n, que gan\u00f3 en la final al Ceuta por 5-1, tras eliminar al Atl\u00e9tico Onubense, Granada y Atl\u00e9tico Algeciras.<\/span><\/p>\n<p><span style=\"color: #008000;\">Benito Villamar\u00edn, 48 a\u00f1os,\u00a0 fue el presidente b\u00e9tico en su d\u00e9cima temporada al frente del club, hasta su dimisi\u00f3n por motivos de salud el 7 de diciembre. Le supli\u00f3 el vicepresidente Avelino Villamar\u00edn, 53 a\u00f1os, hasta la elecci\u00f3n de un nuevo presidente en la asamblea de socios celebrada el 17 de mayo de 1966, cargo que recay\u00f3 en la persona de Andr\u00e9s Gavi\u00f1o, con 57 a\u00f1os.\u00a0<\/span><\/p>\n<p><span style=\"color: #008000;\">La asamblea ordinaria de socios se celebr\u00f3 el 12 de noviembre, mientras que el 17 de mayo se celebr\u00f3 la extraordinaria en la que Andr\u00e9s Gavi\u00f1o fue elegido presidente y se inform\u00f3 del d\u00e9ficit de 1 mill\u00f3n de pesetas con que se cerr\u00f3 la temporada, enjugado con el traspaso de Fernando Ansola al Valencia. <\/span><\/p>\n<p><span style=\"color: #008000;\">La secretar\u00eda del club continuaba establecida en el n\u00famero 11 de la calle Alemanes.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>El 26 de julio en el Villamar\u00edn comienzan los entrenamientos de la primera plantilla b\u00e9tica. Al frente de ella el t\u00e9cnico brasile\u00f1o Martim Francisco, 37 a\u00f1os,\u00a0 presente en el f\u00fatbol espa\u00f1ol desde 1958 en que entren\u00f3 al Athletic. La campa\u00f1a anterior hab\u00eda dirigido al Elche, al que clasific\u00f3 en 8\u00aa posici\u00f3n. En la plantilla b\u00e9tica&#8230;<\/p>\n","protected":false},"author":5,"featured_media":106182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[902,906,1],"tags":[8183,17940,18080,17861,18231],"class_list":["post-106181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1960-1969","category-investigacion-temas","category-portada","tag-1965-66","tag-copa-1965-66","tag-copa-sanchez-pizjuan-1965-66","tag-liga-primera-1965-66","tag-liga-tercera-1965-66"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2025\/12\/Temporada-1965-66.jpg?fit=796%2C607&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-rCB","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/106181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=106181"}],"version-history":[{"count":3,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/106181\/revisions"}],"predecessor-version":[{"id":106187,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/106181\/revisions\/106187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/106182"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=106181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=106181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=106181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}