{"id":31593,"date":"2013-07-17T17:48:08","date_gmt":"2013-07-17T15:48:08","guid":{"rendered":"http:\/\/www.manquepierda.com\/historiarealbetis\/?p=31593"},"modified":"2024-08-19T08:47:10","modified_gmt":"2024-08-19T06:47:10","slug":"1956-campeon-provincial-real-betis-balompie-juvenil-entrevista-al-capitan-blandon","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/1956-campeon-provincial-real-betis-balompie-juvenil-entrevista-al-capitan-blandon\/","title":{"rendered":"1956.-Campe\u00f3n Provincial: Real Betis Balompi\u00e9-Juvenil.-Entrevista al capit\u00e1n Bland\u00f3n."},"content":{"rendered":"<figure id=\"attachment_31594\" aria-describedby=\"caption-attachment-31594\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.manquepierda.com\/historiarealbetis\/31593-1956-campeon-provincial-real-betis-balompie-juvenil-entrevista-al-capitan-blandon\/rbb-j-campeon-provincial-1956\/\" rel=\"attachment wp-att-31594\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-31594\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?resize=680%2C412&#038;ssl=1\" alt=\"\u00a1Oiga\u00a1 04-12-1956.\" width=\"680\" height=\"412\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?resize=680%2C412&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?resize=220%2C133&amp;ssl=1 220w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?resize=960%2C581&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?resize=1024%2C620&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?w=1391&amp;ssl=1 1391w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/a><figcaption id=\"caption-attachment-31594\" class=\"wp-caption-text\">\u00a1Oiga\u00a1 04-12-1956.<\/figcaption><\/figure>\n<p style=\"text-align: center\"><em><strong>\u00abEl Real Betis Balompi\u00e9-Juvenil se ha proclamado campe\u00f3n provincial del primer grupo despu\u00e9s de una brillant\u00edsima campa\u00f1a.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>Tomaron parte en dicho campeonato provincial los siguientes equipos:\u00a0 Sevilla FbC,\u00a0 Real Club Recreativo de Huelva y la Agrupaci\u00f3n Deportiva Cros de San Juan de Aznalfarache.<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>Los campeones han logrado cuatro victorias y un empate;\u00a0 perdieron una sola vez en el partido jugado en Huelva por un gol de diferencia,\u00a0 <\/strong><\/em><strong>lo que nos da una muestra de la potencialidad de los muchachos que con tanto acierto prepara Pepe Pineda.<\/strong><\/p>\n<p style=\"text-align: left\"><strong>Una de las principales figuras del conjunto es\u00a0<em>Bland\u00f3n,\u00a0 <\/em>capit\u00e1n del equipo,\u00a0 que despu\u00e9s de conseguir la \u00faltima victoria no cab\u00eda de alegr\u00eda dentro de su camisol\u00edn verdiblanco.<\/strong><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfPuede el capit\u00e1n de los campeones contestar a unas preguntas?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Estoy tan emocionado ahora mismo,\u00a0 que me parece dif\u00edcil en este momento contestar a ellas,\u00a0 pero pregunte y contestar\u00e9.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfCu\u00e1ntos a\u00f1os llevas en el juvenil del Real Betis Balompi\u00e9?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Tres temporadas.\u00a0 Esta es la tarde que mayor satisfacci\u00f3n he sentido desde que pertenezco al equipo.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfJugadores que intervinieron en \u00e9l?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Ca\u00f1estro,\u00a0 Su\u00e1rez,\u00a0 Rangel,\u00a0 Castellanos,\u00a0 Polo,\u00a0 Clarimijard,\u00a0 Del Valle,\u00a0 Rodr\u00edguez, Bern\u00e1ldez,\u00a0 JUAN\u00cdN-Juan Garc\u00eda D\u00edaz, Rafael JULI\u00c1 Garc\u00eda,\u00a0 Paquito,\u00a0 Manuel ORDAZ Rebollar,\u00a0 Zarco,\u00a0 Vela\u00a0 y\u00a0 Puro como meta suplente.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfEquipo m\u00e1s dif\u00edcil de vencer?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>-El Recreativo de Huelva.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfDispuesto a conseguir el campeonato regional?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Eso esperamos todos,\u00a0 pero no creo que sea empresa f\u00e1cil,\u00a0 ya que nos tenemos que enfrentar a equipos como el Granada,\u00a0 C\u00f3rdoba\u00a0 y\u00a0 Sevilla,\u00a0 muy buenos todos.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfQu\u00e9 figuras de la actualidad ha dado el Juvenil del Real Betis Balompi\u00e9?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;EUGENIO V\u00e1zquez L\u00f3pez,\u00a0 Lu\u00eds DEL SOL Cascajares,\u00a0 Jos\u00e9 RUIZ MESA\u00a0 y\u00a0 Juan SANTISTEBAN Troya,\u00a0 hoy titular del Real Madrid.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfQui\u00e9n de vosotros imitar\u00e1 a los antes citados?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Eso el tiempo lo dir\u00e1.\u00a0 Son varios los que ya destacan,\u00a0 pero me reservo de dar sus nombres.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>&#8211;\u00bfLlegar\u00e9is a ser campeones de Espa\u00f1a?<\/strong><\/p>\n<p style=\"text-align: left\"><em><strong>&#8211;Antes hay que ganar el regional.\u00a0 En nombre de todos mis compa\u00f1eros le dir\u00e9 que haremos un nuevo esfuerzo para conseguirlo.\u00a0 Nosotros en el terreno de juego imitaremos la labor desarrollada,\u00a0 en prueba de cari\u00f1o hacia nuestro equipo que nos vienen demostrando nuestro delegado don Juan Nadal Vigil,\u00a0 el se\u00f1or Pineda\u00a0 y\u00a0 don Juan L\u00f3pez,\u00a0 secretario t\u00e9cnico.<\/strong><\/em><\/p>\n<p style=\"text-align: left\"><strong>Estas fueron las palabras del juvenil b\u00e9tico,\u00a0 al que le deseamos suerte en el campeonato regional que comenzar\u00e1 el pr\u00f3ximo domingo 04 de Diciembre de 1956&#8243;.-Entrevista realizada por J. NIETO.-\u00a1oiga\u00a1 martes 04-12-1956.<\/strong><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.manquepierda.com\/historiarealbetis\/31593-1956-campeon-provincial-real-betis-balompie-juvenil-entrevista-al-capitan-blandon\/espalgra-2-rbb-j-4\/\" rel=\"attachment wp-att-31674\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31674\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/EspAlgra-2-RBB-J-4.jpg?resize=351%2C700&#038;ssl=1\" alt=\"EspAlgra-2 RBB-J-4\" width=\"351\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/EspAlgra-2-RBB-J-4.jpg?resize=351%2C700&amp;ssl=1 351w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/EspAlgra-2-RBB-J-4.jpg?resize=110%2C220&amp;ssl=1 110w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/EspAlgra-2-RBB-J-4.jpg?resize=301%2C600&amp;ssl=1 301w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/EspAlgra-2-RBB-J-4.jpg?w=721&amp;ssl=1 721w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><em><strong>40\u00ba PRESIDENTE REAL BETIS BALOMPI\u00c9-TEMPORADAS 1954-1955 \u00e1 1965-1966 (Martes 07-12-1965 carta dimisi\u00f3n por fuerza mayor, c\u00e1ncer):<\/strong><\/em><\/p>\n<p style=\"text-align: center\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-57815\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/CartaDespedidaBenitoVillamar%C3%ADnPrieto.jpg?resize=587%2C700&#038;ssl=1\" alt=\"\" width=\"587\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/CartaDespedidaBenitoVillamar%C3%ADnPrieto.jpg?resize=587%2C700&amp;ssl=1 587w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/CartaDespedidaBenitoVillamar%C3%ADnPrieto.jpg?resize=184%2C220&amp;ssl=1 184w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/CartaDespedidaBenitoVillamar%C3%ADnPrieto.jpg?resize=503%2C600&amp;ssl=1 503w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/CartaDespedidaBenitoVillamar%C3%ADnPrieto.jpg?resize=768%2C917&amp;ssl=1 768w\" sizes=\"auto, (max-width: 587px) 100vw, 587px\" \/><\/p>\n<p style=\"text-align: left\"><em><strong>DON BENITO VILLAMAR\u00cdN PRIETO.-38 a\u00f1os.-Exportador de Aceitunas.-F\u00e1brica de Conservas Vegetales.-Lora del R\u00edo-Utrera-Sevilla.-Natural de PUGA-To\u00e9n (Ourense), mi\u00e9rcoles 21 de Agosto de 1916.-\u00abCiudad del Betis\u00bb-SEVILLA, lunes 15-Agosto de 1966.-50 A\u00f1os.-D. E. P. Primer Presidente Perpetuo Real Betis Balompi\u00e9.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEl Real Betis Balompi\u00e9-Juvenil se ha proclamado campe\u00f3n provincial del primer grupo despu\u00e9s de una brillant\u00edsima campa\u00f1a. Tomaron parte en dicho campeonato provincial los siguientes equipos:\u00a0 Sevilla FbC,\u00a0 Real Club Recreativo de Huelva y la Agrupaci\u00f3n Deportiva Cros de San Juan de Aznalfarache. Los campeones han logrado cuatro victorias y un empate;\u00a0 perdieron una sola&#8230;<\/p>\n","protected":false},"author":48,"featured_media":31594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[901,17191,893,1],"tags":[1239,4330,168,11369],"class_list":["post-31593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1950-1959","category-cantera","category-jugadores-temas","category-portada","tag-1239","tag-1956-57","tag-betis-juvenil","tag-santiago-blandon"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2013\/07\/RBB-J-Campe%C3%B3n-Provincial-1956.jpg?fit=1391%2C843&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-8dz","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/31593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=31593"}],"version-history":[{"count":1,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/31593\/revisions"}],"predecessor-version":[{"id":95037,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/31593\/revisions\/95037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/31594"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=31593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=31593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=31593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}