{"id":50558,"date":"2016-07-04T07:25:26","date_gmt":"2016-07-04T05:25:26","guid":{"rendered":"http:\/\/www.manquepierda.com\/historiarealbetis\/?p=50558"},"modified":"2016-07-09T22:41:30","modified_gmt":"2016-07-09T20:41:30","slug":"entrevista-rogelio-sosa-1990","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/entrevista-rogelio-sosa-1990\/","title":{"rendered":"Entrevista Rogelio Sosa 1990"},"content":{"rendered":"<figure id=\"attachment_50559\" aria-describedby=\"caption-attachment-50559\" style=\"width: 567px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2016\/07\/Entrevista-Rogelio-Sosa-1990-NMP-Diario-16-Andaluc%C3%ADa-21-05-1990.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-50559 size-full\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2016\/07\/Entrevista-Rogelio-Sosa-1990-NMP-Diario-16-Andaluc%C3%ADa-21-05-1990.jpg?resize=567%2C424&#038;ssl=1\" alt=\"Entrevista Rogelio Sosa 1990 (NMP) Diario 16 Andaluc\u00eda 21-05-1990\" width=\"567\" height=\"424\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2016\/07\/Entrevista-Rogelio-Sosa-1990-NMP-Diario-16-Andaluc%C3%ADa-21-05-1990.jpg?w=567&amp;ssl=1 567w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2016\/07\/Entrevista-Rogelio-Sosa-1990-NMP-Diario-16-Andaluc%C3%ADa-21-05-1990.jpg?resize=220%2C165&amp;ssl=1 220w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><figcaption id=\"caption-attachment-50559\" class=\"wp-caption-text\">Rogelio Sosa en su Coria natal<\/figcaption><\/figure>\n<p>En mayo de 1990, con motivo del ascenso b\u00e9tico a Primera Divisi\u00f3n, el periodista Alejandro Delm\u00e1s realiz\u00f3 en Diario 16 Andaluc\u00eda una entrevista a Rogelio Sosa, en la que rememoraba los ascensos que hab\u00eda vivido: tres como jugador y uno como jugador. La titul\u00f3: Rogelio, memorias de una pierna de caoba<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #008000\"><em>Lo de Los C\u00e1rmenes es lo m\u00e1s importante que me ha pasado a m\u00ed, no s\u00f3lo como ascenso, sino en toda vida de jugador. Ten\u00eda 23 a\u00f1os, y apenas hab\u00eda vivido. Aqu\u00ed, en Villamar\u00edn, lo encarrilamos muy pronto, marqu\u00e9 yo, de falta, luego Quino, y ganamos dos a cero. All\u00ed ganamos cero a uno y ascendimos, y marqu\u00e9 yo tambi\u00e9n, pero las pasamos canutas. Los primeros treinta minutos fueron la leche. Campillo hizo un parad\u00f3n impresionante, Grau sac\u00f3 un bal\u00f3n casi de dentro, y en esto que a la media hora un vole\u00f3n me cae a m\u00ed, \u00d1ito que sale desesperado y yo se la toco por arriba. As\u00ed ascendimos. Era la primavera del 67, casi el verano.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>En la 70-71 y en la 73-74, los ascensos no tienen mucha historia, porque subimos con un mont\u00f3n de puntos de ventaja. De la 70-71 me acuerdo bien de un partido por la ma\u00f1ana en Villamar\u00edn, en que el Castell\u00f3n tra\u00eda un portero muy grande, Corral creo, le metimos cuatro, y yo dos, los dos\u2026 por arriba. Ese a\u00f1o fue con Barrios. Barrios a m\u00ed nunca me dec\u00eda nada, siempre se hinchaba de caf\u00e9, siempre tan bien trajeado, y este hombre que nunca me dec\u00eda nada a m\u00ed, pero un d\u00eda, en Mallorca, el a\u00f1o de Los C\u00e1rmenes, me cogi\u00f3 al principio del t\u00fanel de los vestuarios, y me dijo: \u201cCorre hoy, nada m\u00e1s que hoy\u201d. Le met\u00ed la u\u00f1a, ganamos uno-dos, luego cero-tres en Badalona\u2026 y a Los C\u00e1rmenes.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>En la 73-74 lo mismo, pero all\u00ed todo el mundo hablaba de Aramburu y Mameli\u2026 y los goles los met\u00eda to, catorce o quince. Dec\u00edan que Mameli jugaba muy bien sin bal\u00f3n, je, je, le pasaba como a Iriondo, que entrenaba sin bal\u00f3n, y Biosca se tiraba al suelo muerto de risa, \u201cm\u00edster, me han hecho falta, me muero\u201d.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>En la temporada 73-74 pasa algo en el S\u00e1nchez Pizju\u00e1n\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Esa temporada fue muy f\u00e1cil, ya digo. Vinieron Esnaola, Iglesias, Olmedo, bastantes fichajes. En el campo del Sevilla s\u00f3lo pasa que salgo veinte minutos porque tengo un pinchacito, y le meto una falta por la escuadra a Paco. Perdimos dos-uno, pero en casa les metimos tres. A m\u00ed siempre me ha encantado jugar en esa campo, era una bendici\u00f3n. Otro a\u00f1os, que nos concentramos en el seminario de Umbrete, y Barrios era su entrenador, ganamos all\u00ed dos-tres, me tiraron un huevo duro en el descanso, lo cog\u00ed, lo pel\u00e9, me lo com\u00ed\u2026 y se form\u00f3<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Nos falta la 78-79, Rogelio, segundo de Garc\u00eda Traid\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Ese a\u00f1o se asciende, aparte de todo, porque se repite aquel partido del Ja\u00e9n, gracias a Dios. Pero yo creo que fue el \u00fanico caso en que se echa a un entrenador con \u201cm\u00e1s siete\u201d, como le pas\u00f3 a Jos\u00e9 Luis, que en paz descanse. Es el a\u00f1o del Getafe-Elche. Pero el anterior\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Iriondo\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Es que ese hombre\u2026Si en la final de Copa hubo penaltis y todo y ni me sac\u00f3; lo que pasa es que aquella noche los compa\u00f1eros tuvieron un comportamiento enorme, cogieron la Copa y vinieron a d\u00e1rmela a m\u00ed, cuando yo era, de toda la vida, el que tiraba los penaltis. En 1978, cuando bajamos, y yo me despido en C\u00e1diz, que nada m\u00e1s que salgo Lobato me arrea una patada y luego se disculpa, \u201cperd\u00f3n, maestro, cre\u00ed que era otro\u201d, bueno, pues ese a\u00f1o yo le digo a Iriondo que no se puede reservar gente en Valencia el pen\u00faltimo partido, que all\u00ed hay que puntuar por lo que puedan tramar luego H\u00e9rcules y Burgos. Se quedaron algunos en casa, perdimos uno-cero, y luego, aunque le ganamos a la Real, ya est\u00e1bamos muertos. Recordar, recordar\u2026 Recuerdo el ascenso de Granada y, por el estilo, aquel Carranza, que le ganamos al Benfica<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Andr\u00e9s Bosch\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Siempre me defend\u00eda, \u201c\u00e1nimo chaval, t\u00fa puedes\u201d, y me ense\u00f1\u00f3 que el l\u00edder es aquel a quien el equipo mira cuando el equipo pierde. Y Daucick, con quien debut\u00e9 contra el Madrid, que dec\u00eda \u201cPeque\u00f1as cosas hacen grandes cosas\u201d, y Balmanya, que lleg\u00f3 a ofrecer medio mill\u00f3n de pesetas por m\u00ed cuando me quer\u00edan echar, y Emilio Vara escrib\u00eda que cogiese el tranv\u00eda y me fuese para Coria<\/em><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #008000\"><em>El hombre va rebosando sobre las lunetas ahumadas que protegen la caoba de la luz. El hombre, el fil\u00f3sofo, el psic\u00f3logo, a los 47 a\u00f1os. Da el pen\u00faltimo vistazo a su pasado, a nuestro pasado.<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #008000\"><em>Cuando me echaron del Betis en el 87, despu\u00e9s de treinta a\u00f1os all\u00ed, lo que m\u00e1s me doli\u00f3 fue la forma, c\u00f3mo se hizo. No por el dinero, no, porque ten\u00eda un sueldo cortito, y ya est\u00e1. Yo di todas las facilidades, y me limit\u00e9 a pedir la cuenta. \u00bfEste Betis en Primera? Uff\u2026 Necesita, al menos, tres o cuatro futbolistas para andar con garant\u00edas. Cuando Retamero desmantel\u00f3 el equipo, vino un desbarajuste porque los chavales, por Buenos que sean, necesitan un armaz\u00f3n en el que apoyarse. Yo he convivido con la que creo mejor generaci\u00f3n de jugadores j\u00f3venes de Sevilla, Quino, que una temporada meti\u00f3 31 goles, Dioni, Gonz\u00e1lez, Ant\u00f3n, Demetrio, etc, y no s\u00e9 cu\u00e1ntas veces descendimos entre todos. Me gusta much\u00edsimo Jos\u00e9 Luis Loreto, el de los juveniles, porque no tiene verg\u00fcenza con los defensas. El Betis juega mejor ahora porque Puma ha empezado a pararla. Mientras antes la pongas all\u00ed, m\u00e1s ligero la tienes aqu\u00ed.<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Rogelio, \u00bfQu\u00e9 queda de aquel tiempo?<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Todo ha cambiado una barbaridad, sobre todo las tertulias aquellas nuestras, la convivencia. A todo le llega su tiempo, incluso a Curro Romero, pero ese es especial, porque cualquier d\u00eda es capaz\u2026, como lo que \u00e9l hace no se suele ver, pues, \u00bfEspartaco? Ese es como el Madrid<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Rogelio, la \u201ctost\u00e1\u201d\u2026<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Era un recurso de cuando yo empec\u00e9 a jugaren el Victoria, con Manuel Infantes; pesaba treinta kilos, la ense\u00f1aba con la derecha, y la quitaba con la izquierda, todo muy seguido. Lo hac\u00eda en los salesianos, se lo hice una vez a Griffa en el Metropolitano, y fue a abrazarse con el presidente, a la pista de carboncilla<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>\u00bfQu\u00e9 pensaba Rogelio, qu\u00e9 lloraba, aquella tarde del 66 en que Gardeaz\u00e1bal lo expuls\u00f3 junto a Cabral, y el Sevilla gan\u00f3 uno-dos en Villamar\u00edn, el domingo ante de La Rosaleda?<\/em><\/span><\/li>\n<li><span style=\"color: #008000\"><em>Que hab\u00eda picado, que ellos lo hab\u00edan preparado todo para echarme. Fue un desastre, porque luego no pude jugar en M\u00e1laga, la tarde aquella en que R\u00edos aguantaba en el suelo a Quino en el suelo, \u201cno te levantes, Joaqu\u00edn, no te levantes\u201d \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/em><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En mayo de 1990, con motivo del ascenso b\u00e9tico a Primera Divisi\u00f3n, el periodista Alejandro Delm\u00e1s realiz\u00f3 en Diario 16 Andaluc\u00eda una entrevista a Rogelio Sosa, en la que rememoraba los ascensos que hab\u00eda vivido: tres como jugador y uno como jugador. La titul\u00f3: Rogelio, memorias de una pierna de caoba &nbsp; Lo de Los&#8230;<\/p>\n","protected":false},"author":5,"featured_media":50559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[905,893,1],"tags":[2421,1396],"class_list":["post-50558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1990-1999","category-jugadores-temas","category-portada","tag-2421","tag-rogelio-sosa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2016\/07\/Entrevista-Rogelio-Sosa-1990-NMP-Diario-16-Andaluc%C3%ADa-21-05-1990.jpg?fit=567%2C424&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-d9s","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/50558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=50558"}],"version-history":[{"count":0,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/50558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/50559"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=50558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=50558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=50558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}