{"id":67506,"date":"2024-02-08T12:00:00","date_gmt":"2024-02-08T11:00:00","guid":{"rendered":"http:\/\/www.manquepierda.com\/historiarealbetis\/?p=67506"},"modified":"2024-08-11T15:41:03","modified_gmt":"2024-08-11T13:41:03","slug":"hoy-hace-60-anos-29","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/hoy-hace-60-anos-29\/","title":{"rendered":"Hoy hace 65 a\u00f1os. Betis 5 Sporting 3."},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-67507\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?resize=680%2C462&#038;ssl=1\" alt=\"\" width=\"680\" height=\"462\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?resize=680%2C462&amp;ssl=1 680w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?resize=220%2C149&amp;ssl=1 220w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?resize=75%2C52&amp;ssl=1 75w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?w=689&amp;ssl=1 689w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/a><\/p>\n<p><span style=\"color: #008000\">El 8 de febrero de 1959 el Betis derrota 5-3 al Sporting de Gij\u00f3n en Heli\u00f3polis en partido de la jornada 21 del Campeonato de Liga de Primera Divisi\u00f3n.<\/span><\/p>\n<p><span style=\"color: #008000\">Dos goles de Vila, dos de Moreira y uno de Isidro certifican la victoria verdiblanca ante los asturianos, que marcaron por medio de Biempica, Pl\u00e1 y Ortiz.<\/span><\/p>\n<p><span style=\"color: #008000\">El Betis, entrenado por Antonio Barrios, aline\u00f3 a Men\u00e9ndez (85, Otero); Portu, R\u00edos, Santos; Isidro, Valderas; Casta\u00f1o, Lasa, Vila, Moreira y Del Sol.<\/span><\/p>\n<p><span style=\"color: #008000\">El Sporting, dirigido por Edmundo Su\u00e1rez \u201cMundo\u201d, form\u00f3 con Vera; Medina, Altisent, Sim\u00f3; Pellicer, Pl\u00e1; Rodr\u00edguez I, Biempica, B\u00e1denes, Ortiz y S\u00e1nchez.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 8 de febrero de 1959 el Betis derrota 5-3 al Sporting de Gij\u00f3n en Heli\u00f3polis en partido de la jornada 21 del Campeonato de Liga de Primera Divisi\u00f3n. Dos goles de Vila, dos de Moreira y uno de Isidro certifican la victoria verdiblanca ante los asturianos, que marcaron por medio de Biempica, Pl\u00e1 y&#8230;<\/p>\n","protected":false},"author":5,"featured_media":67507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[901,14583,1],"tags":[1538,17789,15721],"class_list":["post-67506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1950-1959","category-efemerides","category-portada","tag-1538","tag-liga-primera-1958-59","tag-real-sporting-gijon"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2019\/02\/8-1959-Betis-5-Sporting-3-.jpg?fit=689%2C468&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-hyO","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/67506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=67506"}],"version-history":[{"count":1,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/67506\/revisions"}],"predecessor-version":[{"id":92475,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/67506\/revisions\/92475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/67507"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=67506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=67506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=67506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}