{"id":79560,"date":"2023-05-30T11:00:00","date_gmt":"2023-05-30T09:00:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=79560"},"modified":"2024-08-26T20:13:40","modified_gmt":"2024-08-26T18:13:40","slug":"hoy-hace-28-anos-figueres-0-betis-3","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/hoy-hace-28-anos-figueres-0-betis-3\/","title":{"rendered":"Hoy hace 30 a\u00f1os. Figueres 0 Betis 3."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"439\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/05\/30-1993-Figueres-0-Betis-3.jpg?resize=623%2C439&#038;ssl=1\" alt=\"\" class=\"wp-image-79561\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/05\/30-1993-Figueres-0-Betis-3.jpg?w=623&amp;ssl=1 623w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/05\/30-1993-Figueres-0-Betis-3.jpg?resize=220%2C155&amp;ssl=1 220w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><\/figure>\n<\/div>\n\n<p>\u00a0<\/p>\n<p><span style=\"color: #008000\">El 30 de mayo de 1993 en el Nuevo Municipal el Betis derrota 0-3 al Figueres en partido de la jornada 35 del Campeonato de Liga de Segunda Divisi\u00f3n.<\/span><\/p>\n<p><span style=\"color: #008000\">Gordillo hizo dos goles en los minutos 11 y 82, ambos a pase de Luis M\u00e1rquez, y Loreto en el 94 cerr\u00f3 el marcador.<\/span><\/p>\n<p><span style=\"color: #008000\">El Figueres, entrenado por Pichi Alonso, aline\u00f3 a Campos; Russet, Fuertes, Gratac\u00f3s, C\u00e9sar (46, Roura); Valent\u00edn, Pino (75, Dmitrijevic), Dur\u00e1n, M\u00e1rquez; Luis y Markovic.<\/span><\/p>\n<p><span style=\"color: #008000\">El Betis, dirigido por Jos\u00e9 Ram\u00f3n Esnaola, jug\u00f3 con Diezma; Julio, Ure\u00f1a, Ivanov (24, Monreal), Rodolfo; M\u00e1rquez, Ca\u00f1as, Merino, Gordillo (85, Merino II); Tab Ramos y Loreto. \u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 El 30 de mayo de 1993 en el Nuevo Municipal el Betis derrota 0-3 al Figueres en partido de la jornada 35 del Campeonato de Liga de Segunda Divisi\u00f3n. Gordillo hizo dos goles en los minutos 11 y 82, ambos a pase de Luis M\u00e1rquez, y Loreto en el 94 cerr\u00f3 el marcador. El&#8230;<\/p>\n","protected":false},"author":5,"featured_media":79561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[905,14583,1],"tags":[5525,17824,4648],"class_list":["post-79560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1990-1999","category-efemerides","category-portada","tag-5525","tag-liga-segunda-1992-93","tag-ue-figueres"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/05\/30-1993-Figueres-0-Betis-3.jpg?fit=623%2C439&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-kHe","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/79560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=79560"}],"version-history":[{"count":2,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/79560\/revisions"}],"predecessor-version":[{"id":88722,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/79560\/revisions\/88722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/79561"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=79560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=79560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=79560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}