{"id":81575,"date":"2021-09-19T09:07:00","date_gmt":"2021-09-19T07:07:00","guid":{"rendered":"https:\/\/www.manquepierda.com\/historiarealbetis\/?p=81575"},"modified":"2021-09-15T18:26:16","modified_gmt":"2021-09-15T16:26:16","slug":"ganara-por-fin-el-betis-de-luis-carlos-peris","status":"publish","type":"post","link":"https:\/\/www.manquepierda.com\/historiarealbetis\/ganara-por-fin-el-betis-de-luis-carlos-peris\/","title":{"rendered":"\u00bfGanar\u00e1 por fin el Betis?, de Luis Carlos Peris."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"632\" src=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/09\/30-Anuncio-Betis-Espanol.jpg?resize=484%2C632&#038;ssl=1\" alt=\"\" class=\"wp-image-81576\" srcset=\"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/09\/30-Anuncio-Betis-Espanol.jpg?w=484&amp;ssl=1 484w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/09\/30-Anuncio-Betis-Espanol.jpg?resize=459%2C600&amp;ssl=1 459w, https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/09\/30-Anuncio-Betis-Espanol.jpg?resize=168%2C220&amp;ssl=1 168w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/figure><\/div>\n\n\n<p>Esta pregunta era el titular de la columna que dedicaba en su secci\u00f3n Desde mi c\u00f3rner el periodista Luis Carlos Peris el 2 de diciembre de 1990 en la edici\u00f3n de Diario 16 Andaluc\u00eda.<\/p>\n<p>Ese d\u00eda en el Villamar\u00edn comparec\u00eda el Betis para jugar contra el Espanyol, en partido de la jornada\u00a0 13 del Campeonato de Liga de Primera Divisi\u00f3n. El balance hasta ese momento era desolador: el Betis era el \u00faltimo de la clasificaci\u00f3n con 1 victoria, 4 empates y 7 derrotas. Los 6 partidos jugados en casa se hab\u00edan saldado con empates ante Sporting, Zaragoza, Real Sociedad y Oviedo y derrotas ante Barcelona y Sevilla, de forma que a\u00fan no se conoc\u00eda la victoria en el Villamar\u00edn.<\/p>\n<p>El periodista hac\u00eda un recorrido por esta circunstancia, comparando la distinta trayectoria del Espanyol, que era otro reci\u00e9n ascendido como el Betis, pero que se encontraba en una situaci\u00f3n bastante m\u00e1s c\u00f3moda en la mitad de la tabla clasificatoria.<\/p>\n<p>Tambi\u00e9n se comentan algunos aspectos de la actualidad verdiblanca del momento, como el apoyo constante de la afici\u00f3n a pesar de las circunstancias, la renovaci\u00f3n del equipo a base de j\u00f3venes canteranos, las dudas en el eje de la delantera o la llegada de los refuerzos desde el extranjero, como un tal Trifon Ivanov, que fichar\u00eda en la semana siguiente.\u00a0<\/p>\n<p>La mala senda verdiblanca continu\u00f3 en este partido, y a pesar de adelantarse en el marcador con un tempranero gol de Pepe Mel en el minuto 9, al final el conjunto barcelon\u00e9s le dio la vuelta al marcador con tantos de Wutke y M\u00e1gico D\u00edaz.<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"color: #008000\"><em>\u00bfConseguir\u00e1 hoy su primer triunfo casero el Betis? He ah\u00ed una cuesti\u00f3n que se hace esperar m\u00e1s de la cuenta y que ha batido todas las marcas en los ochenta y tres a\u00f1os de vida verdiblanca. Ni siquiera en \u00e9pocas m\u00e1s paup\u00e9rrimas\u2014que las hubo, por cierto\u2014el Real Betis Balompi\u00e9 logr\u00f3 una racha de siete comparecencias caseras sin ganar una sola de ellas. Por lo tanto, batido que fue el ominoso r\u00e9cord, hora es ya de que los b\u00e9ticos vean un triunfo de su equipo.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>Pleitea hoy el Betis ante uno de sus iguales, con un rival que recuper\u00f3 la categor\u00eda con muchas m\u00e1s fatiguitas que los verdiblancos, con m\u00e1s fatigas y con bastante m\u00e1s fortuna, que lo de la tanda de penaltis en La Rosaleda fue demasiado. Ocurri\u00f3 luego sin embargo que el Espa\u00f1ol dise\u00f1\u00f3 un proyecto m\u00e1s ambicioso que el que se gener\u00f3 en Heli\u00f3polis y de ah\u00ed los cinco puntos que hoy le lleva el Betis. Fich\u00f3 a futbolistas de Primera, juega con el cupo de extranjeros al completo y se hizo con los servicios del mejor entrenador espa\u00f1ol, como prueba que Luis Aragon\u00e9s haya salido a subasta en las \u00faltimas semanas. Pero, bueno, el Betis habr\u00e1 de ganar alguna vez y en esas estamos cuando los de Jos\u00e9 Luis Romero embocan una partida m\u00e1s en Villamar\u00edn a sabiendas se que s\u00f3lo les sirve el triunfo para no descolgarse m\u00e1s de lo que est\u00e1n.<\/em><\/span><\/p>\n<p><span style=\"color: #008000\"><em>A favor del Betis, esta tarde y todas las tardes que se abre el recinto de La Palmera, juega lo que tiene detr\u00e1s, el calor incre\u00edble de una afici\u00f3n que todav\u00eda no le ha dedicado un solo grito. Y es una pena que con ese tremendo calor humano que le respalda, el Real Betis Balompi\u00e9 no ponga pies en pared de una vez por todas. Con los j\u00f3venes o sin ellos, con Mel o con Cu\u00e9llar&#8211;\u00bfpor qu\u00e9 no los dos?\u2014el Betis no puede esperar un domingo m\u00e1s, no tiene derecho a seguir vivaqueando por esa zona s\u00f3rdida en la que mora desde que amaneci\u00f3 la Liga. Como sol\u00edan decir los panegiristas de \u00e9pocas anteriores ante cualquier conspiraci\u00f3n judeomas\u00f3nica, ha llegado el momento de decir basta. Basta ya de tambaleos y que gane el Betis, aunque no termine de llegar el llamado Trifon Ivanov. \u00a0\u00a0<\/em><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Esta pregunta era el titular de la columna que dedicaba en su secci\u00f3n Desde mi c\u00f3rner el periodista Luis Carlos Peris el 2 de diciembre de 1990 en la edici\u00f3n de Diario 16 Andaluc\u00eda. Ese d\u00eda en el Villamar\u00edn comparec\u00eda el Betis para jugar contra el Espanyol, en partido de la jornada\u00a0 13 del Campeonato&#8230;<\/p>\n","protected":false},"author":5,"featured_media":81576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,1176],"tags":[2421,3220],"class_list":["post-81575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-relatos-de-futbol","tag-2421","tag-luis-carlos-peris"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.manquepierda.com\/historiarealbetis\/files\/2021\/09\/30-Anuncio-Betis-Espanol.jpg?fit=484%2C632&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1ij08-ldJ","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/81575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/comments?post=81575"}],"version-history":[{"count":0,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/posts\/81575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media\/81576"}],"wp:attachment":[{"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/media?parent=81575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/categories?post=81575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manquepierda.com\/historiarealbetis\/wp-json\/wp\/v2\/tags?post=81575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}